{"id":964,"date":"2026-02-02T17:43:17","date_gmt":"2026-02-02T16:43:17","guid":{"rendered":"https:\/\/williamchevillon.fr\/?p=964"},"modified":"2026-05-06T17:27:35","modified_gmt":"2026-05-06T15:27:35","slug":"janvier-le-temps-setire","status":"publish","type":"post","link":"https:\/\/williamchevillon.fr\/index.php\/2026\/02\/02\/janvier-le-temps-setire\/","title":{"rendered":"Janvier, le temps s&rsquo;\u00e9tire"},"content":{"rendered":"\n<figure><img decoding=\"async\" src=\"https:\/\/williamchevillon.fr\/wp-content\/uploads\/2026\/02\/IMG_20260126_184303.jpg-1022x1024.jpeg\" alt=\"\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Le temps s\u2019\u00e9tire. Je regarde des documentaires sur la conqu\u00eate spatiale apr\u00e8s avoir \u00e9cum\u00e9 les archives de France T\u00e9l\u00e9visions. J\u2019y apprends que Michael Collins n\u2019a pu voir qu\u2019a posteriori ce qu\u2019il s\u2019est pass\u00e9 le 21 juillet 1969, trop concentr\u00e9 sur sa mission essentielle de pilotage et n\u2019ayant pas d\u2019\u00e9cran de t\u00e9l\u00e9vision \u00e0 bord. Soit, on lui a enregistr\u00e9 et je ne sais pas ce que je ferai un jour de cette information, si tant est qu\u2019elle me serve. Sans doute aurais-je pu dire \u00e0 France Travail qu\u2019il m\u2019arrive de retenir des tas de donn\u00e9es qui n\u2019ont pas d\u2019utilit\u00e9 concr\u00e8te dans mon quotidien. Cela aurait \u00e9t\u00e9 plus r\u00e9jouissant que ma \u00e9ni\u00e8me lamentation sur le calcul des indemnit\u00e9s et des carences et sur le fait que r\u00e9parer ma voiture m\u2019a co\u00fbt\u00e9 plus que de raison.<\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Le temps s\u2019\u00e9tire et j\u2019attends. Cela me rappelle le moment o\u00f9, il y a bien vingt-cinq ans, je devais surveiller, apr\u00e8s un apr\u00e8s-midi qui n\u2019en terminait pas, le signal annon\u00e7ant mon tour au cross intercommunal. Je me souviens assez clairement que j\u2019ai brillamment fini troisi\u00e8me dans la cat\u00e9gorie qui m\u2019\u00e9tait alors attribu\u00e9e, celle des CM2 ayant redoubl\u00e9. L\u2019exploit accompli, j\u2019appris en m\u00eame temps que j\u2019\u00e9tais qualifi\u00e9 pour la finale d\u00e9partementale et que le quatri\u00e8me concurrent de mon groupe avait simplement abandonn\u00e9. Ainsi s\u2019acheva ma carri\u00e8re sportive brillante, mais br\u00e8ve.<\/p>\n\n<figure><img decoding=\"async\" src=\"https:\/\/williamchevillon.fr\/wp-content\/uploads\/2026\/02\/131019325_10208810672821431_2001477655129306380_n-1024x683.jpg\" alt=\"\" \/>\n<figcaption>Rare photo de moi en sportif et visiblement motiv\u00e9 \u00e0 l&rsquo;id\u00e9e d&rsquo;\u00eatre sur un terrain.<\/figcaption>\n<\/figure>\n\n<p class=\"wp-block-paragraph\">Lorsque je dis que j\u2019attends, je veux dire aujourd\u2019hui, c\u2019est \u00e9videmment diff\u00e9rent. Je parle d\u2019un signe du Centre national du livre, d\u2019un message de l\u2019ayant droit d\u2019un artiste, d\u2019une validation de l\u2019universit\u00e9\u2026 tout ce qui fait qu\u2019\u00e0 un moment proche, la m\u00e9canique va s\u2019activer, et peut-\u00eatre se gripper, d\u2019un instant \u00e0 l\u2019autre. Le livre sur l\u2019art dans l\u2019espace public est bien avanc\u00e9 et, pour la premi\u00e8re fois depuis des ann\u00e9es, je sens un vide que je n\u2019arrive pas \u00e0 compenser m\u00eame si je fais beaucoup de choses, que les r\u00e9ponses frustrantes aux lettres de motivation ne parviennent pas \u00e0 contredire.<\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Dans la ville, je change mes itin\u00e9raires. Je croise tout de m\u00eame la dame de la laverie, celle qui a daign\u00e9 me dire bonjour le jour o\u00f9 elle avait un service \u00e0 me demander (service que j\u2019ai rendu sans broncher), je revois le gar\u00e7on blond sur sa trottinette \u00e9lectrique, je r\u00e9ponds au vieux monsieur qui parle de la pluie et du vent \u00e0 tous ceux qu\u2019il rencontre. J\u2019identifie qui sont les personnages dont le corps urbain s\u2019irrigue. J\u2019en suis un sans doute. Dans <a style=\"color: #000000;\" href=\"https:\/\/actes-sud.fr\/catalogue\/rue-des-batailles-020447\">son roman<\/a>, Antonin fait remarquer que je parle de la ville comme d\u2019un corps. Je ne parviens pas \u00e0 la penser autrement. J\u2019y vois des organes, des vaisseaux et des influx, tels ceux de ma carcasse. Je continue \u00e0 faire le tour des remparts. J\u00e9r\u00e9mie me taquine en me laissant entendre que c\u2019est un support \u00e0 ma m\u00e9lancolie. Il a raison et, surtout, j\u2019ai toujours besoin d\u2019avoir la t\u00eate en l\u2019air \u00e0 observer les fa\u00e7ades redessin\u00e9es par le halo des lampes \u00e0 sodium et le maigre reflet <a id=\"910\" style=\"color: #000000;\" href=\"https:\/\/williamchevillon.fr\/index.php\/2025\/08\/13\/demain-le-port\/\" type=\"post\">des caseyeurs<\/a> sur l\u2019immense surface noire de la mer.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le temps s\u2019\u00e9tire. Je regarde des documentaires sur la conqu\u00eate spatiale apr\u00e8s avoir \u00e9cum\u00e9 les archives de France T\u00e9l\u00e9visions. J\u2019y apprends que Michael Collins n\u2019a pu voir qu\u2019a posteriori ce qu\u2019il s\u2019est pass\u00e9 le 21 juillet 1969, trop concentr\u00e9 sur sa mission essentielle de pilotage et n\u2019ayant pas d\u2019\u00e9cran de t\u00e9l\u00e9vision \u00e0 bord. Soit, on [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-964","post","type-post","status-publish","format-standard","hentry","category-fragments"],"_links":{"self":[{"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/posts\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":9,"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"predecessor-version":[{"id":975,"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/posts\/964\/revisions\/975"}],"wp:attachment":[{"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/williamchevillon.fr\/index.php\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}